{"id":19796,"date":"2023-11-17T16:05:08","date_gmt":"2023-11-17T14:05:08","guid":{"rendered":"https:\/\/www.vallox.com\/product\/pureo-tx-500-cooling-valve\/"},"modified":"2026-09-02T22:03:30","modified_gmt":"2026-09-02T19:03:30","slug":"pureo-tx-500-cooling-valve","status":"publish","type":"product","link":"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/","title":{"rendered":"Vallox Pureo TX 500 cooling valve"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[303],"product_tag":[],"class_list":["post-19796","product","type-product","status-publish","product_cat-vallox-pureo-accessories","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vallox Pureo TX 500 cooling valve - Vallox<\/title>\n<meta name=\"description\" content=\"Vallox Pureo TX 500 cooling valve\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vallox Pureo TX 500 cooling valve - Vallox\" \/>\n<meta property=\"og:description\" content=\"Vallox Pureo TX 500 cooling valve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/\" \/>\n<meta property=\"og:site_name\" content=\"Vallox\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/valloxoy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T19:03:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/product\\\/pureo-tx-500-cooling-valve\\\/\",\"url\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/product\\\/pureo-tx-500-cooling-valve\\\/\",\"name\":\"Vallox Pureo TX 500 cooling valve - Vallox\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/#website\"},\"datePublished\":\"2023-11-17T14:05:08+00:00\",\"dateModified\":\"2026-09-02T19:03:30+00:00\",\"description\":\"Vallox Pureo TX 500 cooling valve\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/product\\\/pureo-tx-500-cooling-valve\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vallox.com\\\/en\\\/product\\\/pureo-tx-500-cooling-valve\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/product\\\/pureo-tx-500-cooling-valve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vallox Pureo TX 500 cooling valve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/\",\"name\":\"Vallox\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/#organization\",\"name\":\"Vallox Oy\",\"alternateName\":\"Vallox\",\"url\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vallox.com\\\/app\\\/uploads\\\/2026\\\/02\\\/ValloxLogo-HomeSlogan_RGB_Main_500px.webp\",\"contentUrl\":\"https:\\\/\\\/www.vallox.com\\\/app\\\/uploads\\\/2026\\\/02\\\/ValloxLogo-HomeSlogan_RGB_Main_500px.webp\",\"width\":500,\"height\":262,\"caption\":\"Vallox Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vallox.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/valloxoy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vallox-oy\\\/\",\"https:\\\/\\\/www.instagram.com\\\/valloxoy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vallox Pureo TX 500 cooling valve - Vallox","description":"Vallox Pureo TX 500 cooling valve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/","og_locale":"en_US","og_type":"article","og_title":"Vallox Pureo TX 500 cooling valve - Vallox","og_description":"Vallox Pureo TX 500 cooling valve","og_url":"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/","og_site_name":"Vallox","article_publisher":"https:\/\/www.facebook.com\/valloxoy","article_modified_time":"2026-09-02T19:03:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/","url":"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/","name":"Vallox Pureo TX 500 cooling valve - Vallox","isPartOf":{"@id":"https:\/\/www.vallox.com\/en\/#website"},"datePublished":"2023-11-17T14:05:08+00:00","dateModified":"2026-09-02T19:03:30+00:00","description":"Vallox Pureo TX 500 cooling valve","breadcrumb":{"@id":"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vallox.com\/en\/product\/pureo-tx-500-cooling-valve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vallox.com\/en\/"},{"@type":"ListItem","position":2,"name":"Vallox Pureo TX 500 cooling valve"}]},{"@type":"WebSite","@id":"https:\/\/www.vallox.com\/en\/#website","url":"https:\/\/www.vallox.com\/en\/","name":"Vallox","description":"","publisher":{"@id":"https:\/\/www.vallox.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vallox.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.vallox.com\/en\/#organization","name":"Vallox Oy","alternateName":"Vallox","url":"https:\/\/www.vallox.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vallox.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.vallox.com\/app\/uploads\/2026\/02\/ValloxLogo-HomeSlogan_RGB_Main_500px.webp","contentUrl":"https:\/\/www.vallox.com\/app\/uploads\/2026\/02\/ValloxLogo-HomeSlogan_RGB_Main_500px.webp","width":500,"height":262,"caption":"Vallox Oy"},"image":{"@id":"https:\/\/www.vallox.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valloxoy","https:\/\/www.linkedin.com\/company\/vallox-oy\/","https:\/\/www.instagram.com\/valloxoy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.vallox.com\/en\/wp-json\/wp\/v2\/product\/19796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vallox.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vallox.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.vallox.com\/en\/wp-json\/wp\/v2\/media?parent=19796"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vallox.com\/en\/wp-json\/wp\/v2\/product_brand?post=19796"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vallox.com\/en\/wp-json\/wp\/v2\/product_cat?post=19796"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vallox.com\/en\/wp-json\/wp\/v2\/product_tag?post=19796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}